{"id":2642,"date":"2018-10-01T17:56:34","date_gmt":"2018-10-01T20:56:34","guid":{"rendered":"https:\/\/www.eruido.org\/v26\/?p=2642"},"modified":"2026-09-01T18:10:33","modified_gmt":"2026-09-01T21:10:33","slug":"ciudadanos-contra-el-ruido","status":"publish","type":"post","link":"https:\/\/www.eruido.org\/v26\/prensa-videos\/ciudadanos-contra-el-ruido\/","title":{"rendered":"Ciudadanos contra el ruido"},"content":{"rendered":"<div id=\"sumario\" class=\"tb-field\" data-toolset-blocks-field=\"61d2f55873a294828c7eb74face9fbd3\" data-last-update=\"1.4\">\n<p><strong>El Departamento del H\u00e1bitat y Desarrollo Urbano del ITESO, el Observatorio Interdisciplinario del Ruido y Cruzada contra el Ruido presentaron Sim\u00f3n, una plataforma dise\u00f1ada por la empresa chilena eRuido para optimizar la manera en que se miden los niveles de ruido en la ciudad.<\/strong><\/p>\n<\/div>\n<div class=\"tb-field\" data-toolset-blocks-field=\"5a5aa557768f1c1dfb8561a7b8a01bbb\" data-last-update=\"1.4\">\n<p>Son las once de la noche en avenida Chapultepec y el ruido de los escapes sin silenciador llena el ambiente; son las doce y los acordes de \u201cJohnny b. Good\u201d aturden a los vecinos de Casa Musa. Y aunque en el c3 Stage el sonido alcanza a ser contenido dentro del lugar, las vibraciones que se generan tambi\u00e9n hacen lo propio. Los tres puntos descritos son las primeras estaciones de Sim\u00f3n, un sistema de monitoreo de ruido que busca abatir el rezago que hay en el asunto de la inspecci\u00f3n de ruido en la Zona Metropolitana de Guadalajara (ZMG).<\/p>\n<p>El dise\u00f1o y la operaci\u00f3n del sistema de monitoreo est\u00e1n a cargo de eRuido, una compa\u00f1\u00eda chilena que desde 2016 coordina y respalda proyectos relacionados con el ruido urbano. Llega a Guadalajara gracias al trabajo conjunto del Observatorio Interdisciplinario del Ruido, la Cruzada contra el Ruido y el Departamento del H\u00e1bitat y Desarrollo Urbano (DHDU) del ITESO. El objetivo, explica Alberto Garc\u00eda, cofundador de Cruzada contra el Ruido, es \u201cofrecer un sistema de monitoreo constante, p\u00fablico, con un registro hist\u00f3rico, con validez legal, econ\u00f3mico y con micr\u00f3fonos calibrados seg\u00fan la Norma Oficial Mexicana (NOM)\u201d. Y es que, a\u00f1ade Garc\u00eda, uno de los principales problemas con que se han topado desde que comenz\u00f3 la lucha contra el ruido en la zmg es \u201cla obsolescencia de los sistemas para medir el ruido, que son inaccesibles, lentos, corruptibles e ineficientes\u201d. Se busca que los gobiernos municipales adopten la tecnolog\u00eda y la incorporen como parte de las inspecciones.<\/p>\n<p>De momento, a partir de recursos privados, se han instalado tres estaciones de monitoreo: una en la esquina de Chapultepec y Libertad; otra en las inmediaciones del C3 Stage, en Vallarta entre Marsella y Chapultepec; y cerca del centro cultural Casa Musa, en Bosques de la Victoria. Seg\u00fan Isa\u00edas Guevara, de la empresa eRuido, se eligieron estos tres puntos por solicitud de Cruzada contra el Ruido, por el n\u00famero de quejas que acumulaban. Tambi\u00e9n explica que la plataforma posibilita comenzar a grabar los ruidos cuando \u00e9stos rebasan el n\u00famero de decibeles permitidos, lo que facilita recabar evidencia para una eventual denuncia. Por otra parte, tambi\u00e9n permite, a quien est\u00e9 realizando el monitoreo, escuchar en tiempo real cada una de las estaciones.<\/p>\n<p>La operaci\u00f3n de cada una de las estaciones tiene un costo de entre 60 y 80 d\u00f3lares mensuales (entre mil y mil 500 pesos, aproximadamente) y para hacer un monitoreo eficaz de la ZMG ser\u00edan necesarias cerca de 300 estaciones. \u00d3scar Castro, del DHDU del ITESO, explica que el financiamiento no necesariamente tiene que salir del erario, o no en su totalidad, ya que los recursos pueden obtenerse a partir de las multas que se impongan a quienes rebasen los l\u00edmites permitidos de ruido. Por otra parte, el profesor del ITESO se\u00f1ala que se est\u00e1 contemplando instalar un m\u00f3dulo de medici\u00f3n en la Universidad jesuita para monitorear el ruido dentro del campus.<\/p>\n<p>Jaime Hurtado, subdirector de Dict\u00e1menes de Protecci\u00f3n Ambiental de la Procuradur\u00eda Ambiental y del Ordenamiento Territorial de la Ciudad de M\u00e9xico, explica que Sim\u00f3n es un proyecto \u201cinteresante\u201d y recuerda que en la capital del pa\u00eds se realizaron, entre 2008 y 2009, algunos intentos de monitoreo ambiental, aunque no de manera tan focalizada como lo ofrece la plataforma creada por eRuido. Para dimensionar la importancia de regular el ruido, detalla que en la Ciudad de M\u00e9xico las denuncias por ruido excesivo ocupan el tercer lugar, s\u00f3lo debajo de los cambios de uso de suelo y la tala de \u00e1rboles. Tambi\u00e9n a\u00f1ade que en la actualidad se est\u00e1 revisando la Norma Oficial Mexicana (NOM) 081 \u2014en la que se establecen los l\u00edmites m\u00e1ximos permisibles de emisi\u00f3n de ruido y su medici\u00f3n\u2014, con el objetivo de hacer m\u00e1s r\u00edgidos los par\u00e1metros para la capital.<\/p>\n<p>Sim\u00f3n forma parte de una serie de trabajos que ha venido realizando la Cruzada contra el Ruido, que incluye tambi\u00e9n una iniciativa de ley conocida como Ley Antirruido, que fue aprobada el pasado 15 de agosto en el Congreso de Jalisco. Augusto Valencia, diputado de Movimiento Ciudadano por el distrito 6, se\u00f1ala que se trata de una legislaci\u00f3n que no pretende confrontar a empresarios y vecinos, sino crear condiciones para convivir con paz y tranquilidad. El dictamen contempla multas de hasta 40 mil pesos para quienes generen ruido excesivo, as\u00ed como clausuras y revocaci\u00f3n de licencia municipal para los comercios que sean sancionados m\u00e1s de dos veces en un a\u00f1o. La legislaci\u00f3n tambi\u00e9n contempla regulaciones para la pirotecnia y sanciones para los automovilistas que hagan ruido excesivo con el claxon, el mofle o con sus equipos de audio. La ley tambi\u00e9n estipula que las autoridades estatales y municipales deber\u00e1n contar con un sistema de monitoreo para atender reportes y verificar decibeles.<\/p>\n<p>Adem\u00e1s de monitorear los ruidos contaminantes, las estaciones tambi\u00e9n pueden registrar sonidos meteorol\u00f3gicos y de la fauna de las distintas zonas, lo que la hace valiosa, no s\u00f3lo para las autoridades encargadas de sancionar los excesos, sino tambi\u00e9n para quienes estudian los h\u00e1bitats de las diferentes especies que se alojan en la Zona Metropolitana de Guadalajara.<\/p>\n<p>Los interesados en conocer el funcionamiento de la aplicaci\u00f3n pueden entrar a\u00a0<a title=\"Plataforma Simon\" href=\"http:\/\/www.simon.eruido.org\/\" target=\"_blank\" rel=\"noopener\"><em>simon.eruido.org<\/em><\/a>, sitio web en donde es posible consultar la informaci\u00f3n de las tres estaciones piloto que est\u00e1n en operaci\u00f3n.<\/p>\n<p><em>Fuente: <a href=\"https:\/\/magis.iteso.mx\/nota\/ciudadanos-contra-el-ruido\/\" target=\"_blank\" rel=\"nofollow noopener sponsored\">https:\/\/magis.iteso.mx\/nota\/ciudadanos-contra-el-ruido\/<\/a><\/em><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El Departamento del H\u00e1bitat y Desarrollo Urbano del ITESO, el Observatorio Interdisciplinario del Ruido y Cruzada contra el Ruido presentaron Sim\u00f3n, una plataforma dise\u00f1ada por la empresa chilena eRuido para optimizar la manera en que se miden los niveles de ruido en la ciudad.<\/p>\n","protected":false},"author":1,"featured_media":2643,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[41],"tags":[43],"class_list":["post-2642","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prensa-videos","tag-prensa"],"_links":{"self":[{"href":"https:\/\/www.eruido.org\/v26\/wp-json\/wp\/v2\/posts\/2642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eruido.org\/v26\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eruido.org\/v26\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eruido.org\/v26\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eruido.org\/v26\/wp-json\/wp\/v2\/comments?post=2642"}],"version-history":[{"count":5,"href":"https:\/\/www.eruido.org\/v26\/wp-json\/wp\/v2\/posts\/2642\/revisions"}],"predecessor-version":[{"id":2648,"href":"https:\/\/www.eruido.org\/v26\/wp-json\/wp\/v2\/posts\/2642\/revisions\/2648"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eruido.org\/v26\/wp-json\/wp\/v2\/media\/2643"}],"wp:attachment":[{"href":"https:\/\/www.eruido.org\/v26\/wp-json\/wp\/v2\/media?parent=2642"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eruido.org\/v26\/wp-json\/wp\/v2\/categories?post=2642"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eruido.org\/v26\/wp-json\/wp\/v2\/tags?post=2642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}